{"id":10514,"date":"2022-12-21T16:13:29","date_gmt":"2022-12-21T15:13:29","guid":{"rendered":"http:\/\/parcodolomitifriulane.it\/?post_type=i-paesi-del-parco&#038;p=10514"},"modified":"2023-06-06T09:39:02","modified_gmt":"2023-06-06T07:39:02","slug":"montereale-valcellina","status":"publish","type":"i-paesi-del-parco","link":"https:\/\/www.parcodolomitifriulane.it\/en\/i-paesi-del-parco\/montereale-valcellina\/","title":{"rendered":"Montereale Valcellina"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"10514\" class=\"elementor elementor-10514\" data-elementor-post-type=\"i-paesi-del-parco\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8864b5b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8864b5b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c27c38\" data-id=\"4c27c38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42dff4a elementor-widget elementor-widget-text-editor\" data-id=\"42dff4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c8 la porta della Valcellina: qui termina la pianura pordenonese ed inizia la Riserva Naturale della Forra del Cellina. Paese ricco di storia e vivace centro di attivit\u00e0 culturali. La Chiesetta di San Rocco (IX secolo, con successive ristrutturazioni), custodisce gelosamente uno splendido ciclo d\u2019affreschi del \u201cpordenoniano\u201d Calderari e un altare ligneo seicentesco. Un altro ciclo di affreschi (\u2018700) e una pala di G. Narvesa sono conservati nel piccolo oratorio votivo di San Floriano. La secolare centrale idroelettrica di Malnisio, merita sicuramente una visita.<\/p><ul><li>Via M. Ciotti, 122<\/li><li>tel. 0427 798782<\/li><li>fax 0427 799373<\/li><li>sito web:\u00a0<a href=\"http:\/\/www.comune.monterealevalcellina.pn.it\/\" target=\"_blank\" rel=\"noopener\">www.comune.monterealevalcellina.pn.it<\/a><\/li><\/ul><h2>Place to visit<\/h2><h3>THE MALNISIO HYDROELECTRIC PLANT<\/h3><p class=\"translation-block\">The hydroelectric power station of Malnisio is part of a more complex system of plants for the hydroelectric exploitation of the Cellina stream, built in the early \u2018900, thanks to the intuition and project of Aristide Zenari, a young engineer of the Royal Civil Engineers.\nAt the end of 1800, in Valcellina after an evaluation to identify possibilities and methods to build a road linking the villages of Andreis, Barcis, Claut, Cimolais and Erto with plain, Zenari realized that the narrow gorge of Cellina was well-suited to a hydroelectric exploitation.<\/p><h3><span style=\"color: #fdc33c;\"><a style=\"color: #fdc33c;\" href=\"https:\/\/www.parcodolomitifriulane.it\/en\/centro-visite\/centro-visite-riserva-naturale-forra-del-cellina-a-barcis-pn\/\">VISITORS CENTER<\/a><\/span><\/h3><p align=\"justify\">Si trova in localit\u00e0 Ponte Antoi, a Barcis (PN), dove inizia la parte pi\u00f9 significativa della grande incisione che il torrente Cellina ha scavato negli strati calcarei fra Barcis e Montereale prima del suo sbocco nell\u2019alta pianura pordenonese. L\u2019aspetto geomorfologico \u00e8 quello tipico di un grande canyon, il maggiore della regione e senz\u2019altro uno dei pi\u00f9 spettacolari d\u2019Italia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":8875,"parent":0,"menu_order":0,"template":"","categories":[],"area":[94],"class_list":["post-10514","i-paesi-del-parco","type-i-paesi-del-parco","status-publish","has-post-thumbnail","hentry","area-riserva-naturale-forra-del-cellina"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Montereale Valcellina | Parco Dolomiti Friulane<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.parcodolomitifriulane.it\/en\/i-paesi-del-parco\/montereale-valcellina\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montereale Valcellina | Parco Dolomiti Friulane\" \/>\n<meta property=\"og:description\" content=\"\u00c8 la porta della Valcellina: qui termina la pianura pordenonese ed inizia la Riserva Naturale della Forra del Cellina. Paese ricco di storia e vivace centro [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.parcodolomitifriulane.it\/en\/i-paesi-del-parco\/montereale-valcellina\/\" \/>\n<meta property=\"og:site_name\" content=\"Parco Dolomiti Friulane\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dolomitifriulane\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-06T07:39:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.parcodolomitifriulane.it\/wp-content\/uploads\/2015\/10\/montereale_paese-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1020\" \/>\n\t<meta property=\"og:image:height\" content=\"697\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@parcoDF\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/i-paesi-del-parco\\\/montereale-valcellina\\\/\",\"url\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/i-paesi-del-parco\\\/montereale-valcellina\\\/\",\"name\":\"Montereale Valcellina | Parco Dolomiti Friulane\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/i-paesi-del-parco\\\/montereale-valcellina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/i-paesi-del-parco\\\/montereale-valcellina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/montereale_paese-1.jpg\",\"datePublished\":\"2022-12-21T15:13:29+00:00\",\"dateModified\":\"2023-06-06T07:39:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/i-paesi-del-parco\\\/montereale-valcellina\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/i-paesi-del-parco\\\/montereale-valcellina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/i-paesi-del-parco\\\/montereale-valcellina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/montereale_paese-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/montereale_paese-1.jpg\",\"width\":1020,\"height\":697},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/i-paesi-del-parco\\\/montereale-valcellina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I paesi del parco\",\"item\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/i-paesi-del-parco\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Montereale Valcellina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/#website\",\"url\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/\",\"name\":\"Parco Dolomiti Friulane\",\"description\":\"Tutto Straordinariamente Emoz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/#organization\",\"name\":\"Parco Dolomiti Friulane\",\"url\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-1.png\",\"width\":4685,\"height\":2773,\"caption\":\"Parco Dolomiti Friulane\"},\"image\":{\"@id\":\"https:\\\/\\\/www.parcodolomitifriulane.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dolomitifriulane\",\"https:\\\/\\\/x.com\\\/parcoDF\",\"https:\\\/\\\/www.instagram.com\\\/dolomitifriulane\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/DOLOMITIFRIULANEPARK\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Montereale Valcellina | Parco Dolomiti Friulane","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.parcodolomitifriulane.it\/en\/i-paesi-del-parco\/montereale-valcellina\/","og_locale":"en_GB","og_type":"article","og_title":"Montereale Valcellina | Parco Dolomiti Friulane","og_description":"\u00c8 la porta della Valcellina: qui termina la pianura pordenonese ed inizia la Riserva Naturale della Forra del Cellina. Paese ricco di storia e vivace centro [\u2026]","og_url":"https:\/\/www.parcodolomitifriulane.it\/en\/i-paesi-del-parco\/montereale-valcellina\/","og_site_name":"Parco Dolomiti Friulane","article_publisher":"https:\/\/www.facebook.com\/dolomitifriulane","article_modified_time":"2023-06-06T07:39:02+00:00","og_image":[{"width":1020,"height":697,"url":"https:\/\/www.parcodolomitifriulane.it\/wp-content\/uploads\/2015\/10\/montereale_paese-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@parcoDF","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.parcodolomitifriulane.it\/i-paesi-del-parco\/montereale-valcellina\/","url":"https:\/\/www.parcodolomitifriulane.it\/i-paesi-del-parco\/montereale-valcellina\/","name":"Montereale Valcellina | Parco Dolomiti Friulane","isPartOf":{"@id":"https:\/\/www.parcodolomitifriulane.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.parcodolomitifriulane.it\/i-paesi-del-parco\/montereale-valcellina\/#primaryimage"},"image":{"@id":"https:\/\/www.parcodolomitifriulane.it\/i-paesi-del-parco\/montereale-valcellina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.parcodolomitifriulane.it\/wp-content\/uploads\/2015\/10\/montereale_paese-1.jpg","datePublished":"2022-12-21T15:13:29+00:00","dateModified":"2023-06-06T07:39:02+00:00","breadcrumb":{"@id":"https:\/\/www.parcodolomitifriulane.it\/i-paesi-del-parco\/montereale-valcellina\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.parcodolomitifriulane.it\/i-paesi-del-parco\/montereale-valcellina\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.parcodolomitifriulane.it\/i-paesi-del-parco\/montereale-valcellina\/#primaryimage","url":"https:\/\/www.parcodolomitifriulane.it\/wp-content\/uploads\/2015\/10\/montereale_paese-1.jpg","contentUrl":"https:\/\/www.parcodolomitifriulane.it\/wp-content\/uploads\/2015\/10\/montereale_paese-1.jpg","width":1020,"height":697},{"@type":"BreadcrumbList","@id":"https:\/\/www.parcodolomitifriulane.it\/i-paesi-del-parco\/montereale-valcellina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.parcodolomitifriulane.it\/"},{"@type":"ListItem","position":2,"name":"I paesi del parco","item":"https:\/\/www.parcodolomitifriulane.it\/i-paesi-del-parco\/"},{"@type":"ListItem","position":3,"name":"Montereale Valcellina"}]},{"@type":"WebSite","@id":"https:\/\/www.parcodolomitifriulane.it\/#website","url":"https:\/\/www.parcodolomitifriulane.it\/","name":"Parco Dolomiti Friulane","description":"Tutto Straordinariamente Emoz","publisher":{"@id":"https:\/\/www.parcodolomitifriulane.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.parcodolomitifriulane.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.parcodolomitifriulane.it\/#organization","name":"Parco Dolomiti Friulane","url":"https:\/\/www.parcodolomitifriulane.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.parcodolomitifriulane.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.parcodolomitifriulane.it\/wp-content\/uploads\/2022\/06\/cropped-logo-1.png","contentUrl":"https:\/\/www.parcodolomitifriulane.it\/wp-content\/uploads\/2022\/06\/cropped-logo-1.png","width":4685,"height":2773,"caption":"Parco Dolomiti Friulane"},"image":{"@id":"https:\/\/www.parcodolomitifriulane.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dolomitifriulane","https:\/\/x.com\/parcoDF","https:\/\/www.instagram.com\/dolomitifriulane\/","https:\/\/www.youtube.com\/user\/DOLOMITIFRIULANEPARK"]}]}},"_links":{"self":[{"href":"https:\/\/www.parcodolomitifriulane.it\/en\/wp-json\/wp\/v2\/i-paesi-del-parco\/10514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parcodolomitifriulane.it\/en\/wp-json\/wp\/v2\/i-paesi-del-parco"}],"about":[{"href":"https:\/\/www.parcodolomitifriulane.it\/en\/wp-json\/wp\/v2\/types\/i-paesi-del-parco"}],"version-history":[{"count":0,"href":"https:\/\/www.parcodolomitifriulane.it\/en\/wp-json\/wp\/v2\/i-paesi-del-parco\/10514\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.parcodolomitifriulane.it\/en\/wp-json\/wp\/v2\/media\/8875"}],"wp:attachment":[{"href":"https:\/\/www.parcodolomitifriulane.it\/en\/wp-json\/wp\/v2\/media?parent=10514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.parcodolomitifriulane.it\/en\/wp-json\/wp\/v2\/categories?post=10514"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/www.parcodolomitifriulane.it\/en\/wp-json\/wp\/v2\/area?post=10514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}